{"id":6223,"date":"2024-05-01T12:01:39","date_gmt":"2024-05-01T12:01:39","guid":{"rendered":"https:\/\/www.lively.brussels\/?p=6223"},"modified":"2024-05-21T10:03:20","modified_gmt":"2024-05-21T10:03:20","slug":"la-braderie-de-lart","status":"publish","type":"post","link":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/","title":{"rendered":"La Braderie de l\u2019Art"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Cr\u00e9er des \u0153uvres d\u2019art avec des d\u00e9chets recycl\u00e9s, on conna\u00eet.<\/strong><br><strong>Mais le truc avec <a href=\"https:\/\/www.labraderiedelart.com\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\">la Braderie de l\u2019Art de Roubaix<\/a>, c\u2019est que depuis 30 ans, ils ont pouss\u00e9 le concept jusqu\u2019au bout pour devenir le grand rendez-vous artistique, populaire et circulaire du nord de la France.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Et franchement, c\u2019est un truc \u00e0 voir.<\/strong><br>Visite guid\u00e9e avec Sabine d\u2019<a href=\"https:\/\/www.artpointm.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Art Point M, l\u2019asbl qui g\u00e8re le projet.<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_1.jpg\" alt=\"\" class=\"wp-image-6227\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_1.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_1-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_1-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_1-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Bienvenue \u00e0 la Braderie de l&rsquo;Art !<\/figcaption><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>G\u00e9nial concept<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le principe de base \u00e9tait d\u00e9j\u00e0 super lors de la premi\u00e8re \u00e9dition en 1991 (nous y \u00e9tions) et, depuis, il ne cesse de s\u2019enrichir de nouvelles id\u00e9es. <br><strong>En fait, pendant deux jours, des artistes et des collectifs d\u2019artistes cr\u00e9ent des \u0153uvres d\u2019art \u00e0 partir de d\u00e9chets et de mat\u00e9riaux de r\u00e9cup\u00e9ration qui sont mis en vente en direct au public (\u00e0 des prix super-d\u00e9mocratiques).<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Et l\u2019ambiance est carr\u00e9ment au rendez-vous <\/strong>avec cet esprit festif braderie et brocante si typique du pays des Chtis et autres Picards. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>On visite, on discute, on n\u00e9gocie, on trinque et on grignote en rencontrant des artistes venus du monde entier qui d\u00e9coupent, scient, assemblent et d\u00e9corent ces mat\u00e9riaux sous nos yeux pour en faire des \u0153uvres originales et uniques.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_6.jpg\" alt=\"\" class=\"wp-image-6224\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_6.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_6-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_6-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_6-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Artisanat cr\u00e9atif !<\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab\u00a0<em>D\u00e8s le d\u00e9but, l\u2019id\u00e9e c\u2019est de cr\u00e9er une bulle o\u00f9 les \u0153uvres d\u2019art ne seraient pas ch\u00e8res. <\/em><br><br><em>Et donc, pour qu\u2019elles ne soient pas ch\u00e8res, il fallait que les mati\u00e8res premi\u00e8res n\u2019aient plus de valeur. D\u2019o\u00f9 l\u2019id\u00e9e de la r\u00e9cup\u2019 \u00e0 l\u2019\u00e9poque. <\/em><br><em>Et \u00e7a a march\u00e9<\/em>\u00a0\u00bb.<\/p><cite>Sabine d\u2019Art Point M<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Et, depuis sa cr\u00e9ation, ce concept original est toujours le m\u00eame. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Au moins 150 cr\u00e9atrices et cr\u00e9ateurs internationaux invit\u00e9s, des designers, des sculpteurs, des grapheurs, des peintres et artistes iconoclastes qui d\u00e9ploient leurs talents pendant ces deux jours d\u2019\u00e9v\u00e8nement dans une friche industrielle r\u00e9am\u00e9nag\u00e9e qui accueille pr\u00e8s de 20.000 visiteurs \u00e0 chaque \u00e9dition. <\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_3.jpg\" alt=\"\" class=\"wp-image-6231\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_3.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_3-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_3-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_3-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Les artistes et cr\u00e9at\u00b7eur\u00b7trice\u00b7s sont pr\u00eat\u00b7e\u00b7s \u00e0 vous recevoir. <\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Et depuis quelques ann\u00e9es, la Braderie de l\u2019Art met \u00e0 l\u2019honneur \u00e0 chaque \u00e9dition une ville du monde et sa culture. On a eu ainsi Barcelone, Londres, New York ou Rio et, <strong>pour bient\u00f4t, on nous annonce le Qu\u00e9bec <\/strong>(avec m\u00eame <a href=\"https:\/\/www.ofqj.org\/braderie-de-lart-de-roubaix-2022\/\" target=\"_blank\" rel=\"noreferrer noopener\">un appel \u00e0 participation du c\u00f4t\u00e9 de la Belle Province<\/a>). <br>App\u00e9tissant, n\u2019est-ce pas\u00a0?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>\u00ab\u00a0<\/em><\/strong><em>En fait, la braderie de l\u2019art, c\u2019est vraiment un immense atelier de 2\u2009000\u00a0m\u00b2 de cr\u00e9atrices et de cr\u00e9ateurs, un \u00e9v\u00e9nement authentique, un peu hors norme, o\u00f9 \u00e7a travaille en live. <\/em><\/p><p><em>\u00c7a meule, \u00e7a soude, \u00e7a bombe. <\/em><br><em>Il y a des odeurs et du bruit. <\/em><br><em>\u00c7a cr\u00e9e aussi cette ambiance si particuli\u00e8re\u00a0\u00bb.<\/em><\/p><cite>Sabine d\u2019Art Point M<\/cite><\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_10.jpg\" alt=\"\" class=\"wp-image-6235\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_10.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_10-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_10-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_10-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Quelle oeuvre sortira de ce fourneau ? <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_11.jpg\" alt=\"\" class=\"wp-image-6237\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_11.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_11-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_11-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_11-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>\u00c7a a d\u00e9j\u00e0 l&rsquo;air chouette ! <\/figcaption><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Arts nouveaux<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.labraderiedelart.com\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>La Braderie de l\u2019Art, c\u2019est avant tout le rendez-vous de l\u2019art populaire. <\/strong><\/a><br>Parce qu\u2019une grosse partie du boulot de Sabine et de ses coll\u00e8gues d\u2019Art Point M, c\u2019est de <strong>rester \u00e0 l\u2019affut des tendances cr\u00e9atives les plus trendy et les plus originales.<\/strong> Parce qu\u2019il ne s\u2019agirait pas de s\u2019encro\u00fbter dans du d\u00e9j\u00e0-vu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du coup, l\u2019un des grands secrets de cet \u00e9v\u00e8nement si r\u00e9ussi, c\u2019est la relation \u00e9tablie avec ces artistes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>\u00ab\u00a0C\u2019est essentiel pour nous de rester en contact avec les mutations et les cr\u00e9ateurs de notre \u00e9poque. <\/strong><\/em><br><em>On s\u2019efforce toujours de <strong>capter des jeunes designers et designeuses qui ont vraiment envie de travailler avec leurs dix\u00a0doigts et de cr\u00e9er des \u0153uvres uniques.<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les artistes sont s\u00e9lectionn\u00e9s sur dossier, leur emplacement leur est fourni gratuitement et tous les mat\u00e9riaux sont mis \u00e0 disposition. <\/em><br><em>Nous, on leur assure aussi \u00e0 boire, \u00e0 manger et \u00e0 dormir sur place pendant ces deux jours\u00a0\u00bb.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_12.jpg\" alt=\"\" class=\"wp-image-6239\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_12.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_12-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_12-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_12-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Les artistes choissisent leurs mat\u00e9riaux. <br>Que vont-ils nous faire de beau avec \u00e7a ? <\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u00ab\u00a0Pour conserver cet esprit de la Braderie de l\u2019Art, les \u0153uvres sont vendus entre 1 \u20ac et 300 \u20ac. <\/em><\/p><p><em>Et, comme \u00e7a, l\u2019art est \u00e0 port\u00e9e de tous pendant 24\u00a0heures non-stop\u00a0\u00bb.<\/em><\/p><cite>Sabine d\u2019Art Point M<\/cite><\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_8.jpg\" alt=\"\" class=\"wp-image-6242\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_8.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_8-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_8-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_8-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Vous pourriez, par exemple, repartir avec ceci ? <\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_14.jpg\" alt=\"\" class=\"wp-image-6247\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_14.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_14-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_14-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_14-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Ou alors avec \u00e7a ? <\/figcaption><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Circulaire par nature<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les mat\u00e9riaux et autres d\u00e9chets mis \u00e0 disposition des cr\u00e9atrices et cr\u00e9ateurs viennent directement de rebuts et d\u2019invendus fournis par les entreprises locales. <\/strong><br>Aujourd\u2019hui, la machine est franchement bien r\u00f4d\u00e9e et fonctionne tr\u00e8s bien.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab\u00a0<em>Au d\u00e9but, c\u2019est vrai qu\u2019on faisait de l\u2019\u00e9conomie circulaire sans le savoir. <\/em><\/strong><br><em>On la vivait et on l\u2019exp\u00e9rimentait mais sans la conceptualiser comme aujourd\u2019hui. On faisait nos collectes dans <a href=\"https:\/\/www.label-emmaus.co\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">les Emma\u00fcs<\/a> (l\u2019\u00e9quivalent des <a href=\"https:\/\/petitsriens.be\/\" target=\"_blank\" rel=\"noreferrer noopener\">Petits Riens \u00e0 Bruxelles<\/a>) et aupr\u00e8s de quelques entreprises par-ci par-l\u00e0. <\/em><br><strong><em>Puis, avec le temps, on a perfectionn\u00e9 le syst\u00e8me notamment en cr\u00e9ant un label en 2013 pour les entreprises locales qui nous fournissent ces mati\u00e8res premi\u00e8res. <\/em><br><em>Du coup, elles aussi y voient un int\u00e9r\u00eat.<\/em><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_13.jpg\" alt=\"\" class=\"wp-image-6245\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_13.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_13-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_13-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_13-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Une fois les mat\u00e9riaux choisis, on r\u00e9fl\u00e9chit et on cr\u00e9\u00e9. <\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Et c\u2019est vrai que c\u2019est devenu une partie importante de notre travail. <\/em><br><em>Rencontrer ces entreprises, identifier les mati\u00e8res et mat\u00e9riaux disponibles, r\u00e9fl\u00e9chir aux formes et aux usages\u2026<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Et, ce qu\u2019on constate aujourd\u2019hui, c\u2019est que ces entreprises qui jouent le jeu sont devenues de vrais partenaires. <\/strong><\/em><br><em>Leurs collaborateurs aiment bien voir ce que les artistes font de leurs mat\u00e9riaux de travail, \u00e7a les int\u00e9resse.<\/em><br><em>Et on a aussi pas mal d\u2019entreprises d\u2019insertion dans ce r\u00e9seau. Elles sont souvent tr\u00e8s motiv\u00e9es<\/em>\u00a0\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_5.jpg\" alt=\"\" class=\"wp-image-6251\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_5.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_5-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_5-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_5-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>On est curieux de voir ce qu&rsquo;ils vont faire de beau avec \u00e7a. <\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u00ab\u00a0Pour nous, en tant qu\u2019acteur culturel, c\u2019est super important de cr\u00e9er ces boucles de soci\u00e9t\u00e9s entre \u00e9conomie locale, citoyennet\u00e9, insertion sociale et \u00e9conomie circulaire. <\/em><br><br><em>On a ainsi une plus grande place dans la cit\u00e9\u00a0\u00bb.<\/em><\/p><cite>Sabine d\u2019Art Point M<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">D\u2019un point de vue purement circulaire, <strong>les r\u00e9sultats de la Braderie de l\u2019Art sont aussi impressionnants puisque l\u2019asbl Art Point M estime que ce sont \u00e0 chaque fois pr\u00e8s de 2000 m\u00e8tres cube de brol qui sont retravaill\u00e9s et mis en vente, <\/strong>soit en trente ans, pr\u00e8s de 6000 m\u00e8tres cube. <br>Pas mal, effectivement.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00c0 vous les artistes et amateurs<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>On l\u2019aura compris, <a href=\"https:\/\/www.labraderiedelart.com\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\">la Braderie de l\u2019Art<\/a>, c\u2019est un fabuleux espace de rencontres entre cr\u00e9atrices et cr\u00e9ateurs d\u2019une part et amateurs d\u2019art et de design original et pas cher, d\u2019autre part.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour l\u2019avoir fait, on vous le confirme, on rentre \u00e0 la maison avec des \u0153uvres \u00e9tonnantes, uniques, esth\u00e9tiques, parfois bizarres et souvent surprenantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>On parle beaucoup de d\u00e9mocratiser l\u2019art et la culture. <br>Eh bien l\u00e0, c\u2019est clair, on y est\u00a0!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Si vous \u00eates amatrices ou amateurs d\u2019art, de culture, de design underground, de d\u00e9co d\u00e9cal\u00e9e ou juste simplement d\u2019\u00e9v\u00e8nements populaires et festifs, vous devez noter la Braderie de l\u2019Art dans vos tablettes.<br><a href=\"https:\/\/www.labraderiedelart.com\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\">C\u2019est facile, c\u2019est le week-end des 3 et 4 d\u00e9cembre prochains \u00e0 la Condition Publique \u00e0 Roubaix.<\/a><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_15.jpg\" alt=\"\" class=\"wp-image-6255\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_15.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_15-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_15-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_15-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>Et c&rsquo;est clair qu&rsquo;on s&rsquo;amuse vraiment !<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Et, attention, si vous avez des vell\u00e9it\u00e9s artistiques (un peu confirm\u00e9es quand m\u00eame) et que la participation \u00e0 ce m\u00e9ga-event artistique, populaire et sympa vous int\u00e9resse, n\u2019h\u00e9sitez pas\u00a0! <br><a href=\"https:\/\/www.labraderiedelart.com\/fr\/inscription\" target=\"_blank\" rel=\"noreferrer noopener\">Pr\u00e9sentez-vous\u00a0!<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quelques infos sur ce qui vous attend si vous vous lancez\u00a0:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00ab\u00a0<em>On envoie juste un dossier aux cr\u00e9atrices et aux cr\u00e9ateurs dans lequel on leur demande\u00a0: <\/em><br><em>Qui \u00eates-vous\u00a0? Qu\u2019est-ce que vous faites\u2009? <\/em><br><em>Et surtout, qu\u2019est-ce que vous avez envie de faire \u00e0 la braderie de l\u2019art\u2009? Et \u00e0 partir de quels mat\u00e9riaux\u2009?<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>En on re\u00e7oit \u00e0 peu pr\u00e8s 300\u00a0dossiers chaque ann\u00e9e. <\/em><br><em>Et l\u00e0-dedans, on en prend 150. Donc c\u2019est moiti\u00e9-moiti\u00e9. <\/em><\/strong><br><em>Mais c\u2019est vrai que c\u2019est de plus en plus quasiment de la programmation. C\u2019est-\u00e0-dire que c\u2019est nous qui allons parfois vers les artistes et les collectifs.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Notre travail c\u2019est vraiment d\u2019\u00eatre au taquet sur ce qui se passe dans tel ou tel atelier. <\/em><br><em>L\u00e0, par exemple, on est \u00e0 fond dans le textile. <\/em><\/strong><br><em>Parce qu\u2019avec les probl\u00e8mes li\u00e9s \u00e0 la fast fashion notamment, le textile devient une mati\u00e8re \u00e0 part enti\u00e8re et avec des process de design d\u00e9j\u00e0 tr\u00e8s int\u00e9ressants\u00a0\u00bb.<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_9.jpg\" alt=\"\" class=\"wp-image-6257\" srcset=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_9.jpg 750w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_9-300x200.jpg 300w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_9-610x407.jpg 610w, https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_9-640x427.jpg 640w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption>C&rsquo;est beau, original, unique et pas cher. <\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u00ab\u00a0C\u2019est tr\u00e8s stimulant pour nous de travailler avec de jeunes \u00e9tudiants, des futurs professionnels, des couturi\u00e8res, des \u00e9l\u00e8ves d\u2019\u00e9coles de mode\u2026 <\/em><\/p><p><em>Donc c\u2019est vrai, le textile c\u2019est l\u2019un de nos prochains sujets pour les deux ou trois \u00e9ditions \u00e0 venir\u00a0\u00bb.<\/em><\/p><cite>Sabine d\u2019Art Point M<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Donc, si vous avez dix doigts bien huil\u00e9s, des id\u00e9es, quelques r\u00e9alisations et surtout l\u2019envie de participer \u00e0 l\u2019un des \u00e9v\u00e8nements les plus sympas du moment, allez-y\u00a0! Foncez\u00a0!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/www.labraderiedelart.com\/fr\/home\" target=\"_blank\" rel=\"noreferrer noopener\">Et pour les autres, on s\u2019y retrouve, cet hiver\u00a0!<\/a><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cr\u00e9dits photos :<\/strong> <a href=\"https:\/\/www.artpointm.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Art Point M. <\/a>\/ Jacob Khrist \/ Sophie Stalnikiewicz<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"105\" src=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2021\/12\/by-nc-sa.eu_-300x105-3.png\" alt=\"\" class=\"wp-image-5523\"\/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center has-small-font-size wp-block-paragraph\"><a href=\"https:\/\/www.lively.brussels\/index.php\/2020\/09\/30\/creative-come-on\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cet article est sous Licence Creative Commons.<\/a><br>Vous \u00eates libre de le r\u00e9utiliser (en mentionnant l\u2019auteur \u2013 BY) mais pas pour un usage commercial (NC) et pour le partager dans les m\u00eames conditions (SA).<br><a href=\"https:\/\/creativecommons.org\/licenses\/?lang=fr\" target=\"_blank\" rel=\"noreferrer noopener\">All about Creative Commons<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9atif, populaire et circulaire<\/p>\n","protected":false},"author":2,"featured_media":6261,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[302,237,276],"tags":[313,253,20,153],"class_list":["post-6223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cadeaux","category-creativite","category-design","tag-art-populaire","tag-creativite","tag-design","tag-economie-circulaire","entry-card--landscape"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire<\/title>\n<meta name=\"description\" content=\"Le Webmagazine de l&#039;\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire\" \/>\n<meta property=\"og:description\" content=\"Le Webmagazine de l&#039;\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/\" \/>\n<meta property=\"og:site_name\" content=\"LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LivelyBrussels\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T12:01:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T10:03:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@BrusselsLively\" \/>\n<meta name=\"twitter:site\" content=\"@BrusselsLively\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/\"},\"author\":{\"name\":\"Dan\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#\\\/schema\\\/person\\\/27b8da6d7e6a73c586858220b3689813\"},\"headline\":\"La Braderie de l\u2019Art\",\"datePublished\":\"2024-05-01T12:01:39+00:00\",\"dateModified\":\"2024-05-21T10:03:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/\"},\"wordCount\":1621,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg\",\"keywords\":[\"Art populaire\",\"Cr\u00e9ativit\u00e9\",\"Design\",\"Economie circulaire\"],\"articleSection\":[\"Cadeaux\",\"Cr\u00e9ativit\u00e9\",\"DESIGN\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/\",\"url\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/\",\"name\":\"La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg\",\"datePublished\":\"2024-05-01T12:01:39+00:00\",\"dateModified\":\"2024-05-21T10:03:20+00:00\",\"description\":\"Le Webmagazine de l'\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/2024\\\/05\\\/01\\\/la-braderie-de-lart\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.lively.brussels\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Braderie de l\u2019Art\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#website\",\"url\":\"https:\\\/\\\/www.lively.brussels\\\/\",\"name\":\"LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire\",\"description\":\"Pour tout savoir de l&#039;\u00e9conomie circulaire \u00e0 Bruxelles, en Belgique et dans le reste de l&#039;univers\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lively.brussels\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#organization\",\"name\":\"Sense Brussels SCRL\",\"url\":\"https:\\\/\\\/www.lively.brussels\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lively_Favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lively.brussels\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Lively_Favicon.jpg\",\"width\":134,\"height\":134,\"caption\":\"Sense Brussels SCRL\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LivelyBrussels\\\/\",\"https:\\\/\\\/x.com\\\/BrusselsLively\",\"https:\\\/\\\/www.instagram.com\\\/livelybrussels\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lively-brussels\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lively.brussels\\\/#\\\/schema\\\/person\\\/27b8da6d7e6a73c586858220b3689813\",\"name\":\"Dan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g\",\"caption\":\"Dan\"},\"url\":\"https:\\\/\\\/www.lively.brussels\\\/index.php\\\/author\\\/remade_dan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire","description":"Le Webmagazine de l'\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/","og_locale":"fr_FR","og_type":"article","og_title":"La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire","og_description":"Le Webmagazine de l'\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.","og_url":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/","og_site_name":"LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire","article_publisher":"https:\/\/www.facebook.com\/LivelyBrussels\/","article_published_time":"2024-05-01T12:01:39+00:00","article_modified_time":"2024-05-21T10:03:20+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg","type":"image\/jpeg"}],"author":"Dan","twitter_card":"summary_large_image","twitter_creator":"@BrusselsLively","twitter_site":"@BrusselsLively","twitter_misc":{"\u00c9crit par":"Dan","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#article","isPartOf":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/"},"author":{"name":"Dan","@id":"https:\/\/www.lively.brussels\/#\/schema\/person\/27b8da6d7e6a73c586858220b3689813"},"headline":"La Braderie de l\u2019Art","datePublished":"2024-05-01T12:01:39+00:00","dateModified":"2024-05-21T10:03:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/"},"wordCount":1621,"commentCount":0,"publisher":{"@id":"https:\/\/www.lively.brussels\/#organization"},"image":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg","keywords":["Art populaire","Cr\u00e9ativit\u00e9","Design","Economie circulaire"],"articleSection":["Cadeaux","Cr\u00e9ativit\u00e9","DESIGN"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/","url":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/","name":"La Braderie de l\u2019Art &#060; LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire","isPartOf":{"@id":"https:\/\/www.lively.brussels\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#primaryimage"},"image":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg","datePublished":"2024-05-01T12:01:39+00:00","dateModified":"2024-05-21T10:03:20+00:00","description":"Le Webmagazine de l'\u00e9conomie circulaire \u00e0 Bruxelles, de la transition \u00e9conomique et de la durabilit\u00e9.","breadcrumb":{"@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#primaryimage","url":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg","contentUrl":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2022\/09\/2022-09-07-LIVELY-POST_97_Braderie-de-l-Art_16.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.lively.brussels\/index.php\/2024\/05\/01\/la-braderie-de-lart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lively.brussels\/"},{"@type":"ListItem","position":2,"name":"La Braderie de l\u2019Art"}]},{"@type":"WebSite","@id":"https:\/\/www.lively.brussels\/#website","url":"https:\/\/www.lively.brussels\/","name":"LIVELY - Le WebMag de l&#039;\u00e9conomie circulaire","description":"Pour tout savoir de l&#039;\u00e9conomie circulaire \u00e0 Bruxelles, en Belgique et dans le reste de l&#039;univers","publisher":{"@id":"https:\/\/www.lively.brussels\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lively.brussels\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lively.brussels\/#organization","name":"Sense Brussels SCRL","url":"https:\/\/www.lively.brussels\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lively.brussels\/#\/schema\/logo\/image\/","url":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2020\/08\/Lively_Favicon.jpg","contentUrl":"https:\/\/www.lively.brussels\/wp-content\/uploads\/2020\/08\/Lively_Favicon.jpg","width":134,"height":134,"caption":"Sense Brussels SCRL"},"image":{"@id":"https:\/\/www.lively.brussels\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LivelyBrussels\/","https:\/\/x.com\/BrusselsLively","https:\/\/www.instagram.com\/livelybrussels\/","https:\/\/www.linkedin.com\/company\/lively-brussels"]},{"@type":"Person","@id":"https:\/\/www.lively.brussels\/#\/schema\/person\/27b8da6d7e6a73c586858220b3689813","name":"Dan","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c44b4e64c6affe7d245ec199692d5edbd481f3147a0239eef7565f0ac162043?s=96&d=mm&r=g","caption":"Dan"},"url":"https:\/\/www.lively.brussels\/index.php\/author\/remade_dan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/posts\/6223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/comments?post=6223"}],"version-history":[{"count":26,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/posts\/6223\/revisions"}],"predecessor-version":[{"id":6263,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/posts\/6223\/revisions\/6263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/media\/6261"}],"wp:attachment":[{"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/media?parent=6223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/categories?post=6223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lively.brussels\/index.php\/wp-json\/wp\/v2\/tags?post=6223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}